{"id":900,"date":"2025-05-02T18:21:24","date_gmt":"2025-05-02T18:21:24","guid":{"rendered":"https:\/\/www.bloominblinds.com\/rochester-hills\/?page_id=900"},"modified":"2025-05-02T18:21:26","modified_gmt":"2025-05-02T18:21:26","slug":"motorized-window-treatments-change","status":"publish","type":"page","link":"https:\/\/www.bloominblinds.com\/rochester-hills\/motorized-window-treatments-change\/","title":{"rendered":"Motorized window treatments Change"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-900","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/pages\/900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":1,"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/pages\/900\/revisions"}],"predecessor-version":[{"id":901,"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/pages\/900\/revisions\/901"}],"wp:attachment":[{"href":"https:\/\/www.bloominblinds.com\/rochester-hills\/wp-json\/wp\/v2\/media?parent=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}